{"id":201,"count":0,"description":"","link":"https:\/\/collall.nl\/fr\/product-category\/idees-creatives\/","name":"Id\u00e9es cr\u00e9atives","slug":"idees-creatives","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":8,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Id\u00e9es cr\u00e9atives Archives - Collall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/collall.nl\/fr\/product-category\/idees-creatives\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Id\u00e9es cr\u00e9atives Archives - Collall\" \/>\n<meta property=\"og:url\" content=\"https:\/\/collall.nl\/fr\/product-category\/idees-creatives\/\" \/>\n<meta property=\"og:site_name\" content=\"Collall\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/collall.nl\\\/fr\\\/product-category\\\/idees-creatives\\\/\",\"url\":\"https:\\\/\\\/collall.nl\\\/fr\\\/product-category\\\/idees-creatives\\\/\",\"name\":\"Id\u00e9es cr\u00e9atives Archives - Collall\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/collall.nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/collall.nl\\\/fr\\\/product-category\\\/idees-creatives\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/collall.nl\\\/fr\\\/product-category\\\/idees-creatives\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/collall.nl\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Id\u00e9es cr\u00e9atives\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/collall.nl\\\/#website\",\"url\":\"https:\\\/\\\/collall.nl\\\/\",\"name\":\"Collall\",\"description\":\"Adhesives &amp; Paints since 1949\",\"publisher\":{\"@id\":\"https:\\\/\\\/collall.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/collall.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/collall.nl\\\/#organization\",\"name\":\"Collall B.V.\",\"url\":\"https:\\\/\\\/collall.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/collall.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/collall.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Collall-logo-186C_Reflex-blue.jpg\",\"contentUrl\":\"https:\\\/\\\/collall.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Collall-logo-186C_Reflex-blue.jpg\",\"width\":1963,\"height\":1179,\"caption\":\"Collall B.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/collall.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Collall\\\/100064976852539\\\/\",\"https:\\\/\\\/www.instagram.com\\\/collall_1949\\\/\",\"https:\\\/\\\/nl.pinterest.com\\\/CollallBV\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCrCGuwth_udZhTqJSh5g9zg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Id\u00e9es cr\u00e9atives Archives - Collall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/collall.nl\/fr\/product-category\/idees-creatives\/","og_locale":"fr_FR","og_type":"article","og_title":"Id\u00e9es cr\u00e9atives Archives - Collall","og_url":"https:\/\/collall.nl\/fr\/product-category\/idees-creatives\/","og_site_name":"Collall","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/collall.nl\/fr\/product-category\/idees-creatives\/","url":"https:\/\/collall.nl\/fr\/product-category\/idees-creatives\/","name":"Id\u00e9es cr\u00e9atives Archives - Collall","isPartOf":{"@id":"https:\/\/collall.nl\/#website"},"breadcrumb":{"@id":"https:\/\/collall.nl\/fr\/product-category\/idees-creatives\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/collall.nl\/fr\/product-category\/idees-creatives\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/collall.nl\/fr\/"},{"@type":"ListItem","position":2,"name":"Id\u00e9es cr\u00e9atives"}]},{"@type":"WebSite","@id":"https:\/\/collall.nl\/#website","url":"https:\/\/collall.nl\/","name":"Collall","description":"Adhesives &amp; Paints since 1949","publisher":{"@id":"https:\/\/collall.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/collall.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/collall.nl\/#organization","name":"Collall B.V.","url":"https:\/\/collall.nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/collall.nl\/#\/schema\/logo\/image\/","url":"https:\/\/collall.nl\/wp-content\/uploads\/2022\/08\/Collall-logo-186C_Reflex-blue.jpg","contentUrl":"https:\/\/collall.nl\/wp-content\/uploads\/2022\/08\/Collall-logo-186C_Reflex-blue.jpg","width":1963,"height":1179,"caption":"Collall B.V."},"image":{"@id":"https:\/\/collall.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Collall\/100064976852539\/","https:\/\/www.instagram.com\/collall_1949\/","https:\/\/nl.pinterest.com\/CollallBV\/","https:\/\/www.youtube.com\/channel\/UCrCGuwth_udZhTqJSh5g9zg"]}]}},"_links":{"self":[{"href":"https:\/\/collall.nl\/fr\/wp-json\/wp\/v2\/product_cat\/201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collall.nl\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/collall.nl\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/collall.nl\/fr\/wp-json\/wp\/v2\/product?product_cat=201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}